{"id":37331,"date":"2023-12-04T10:59:50","date_gmt":"2023-12-04T10:59:50","guid":{"rendered":"https:\/\/www.naxosvacanze.net\/?post_type=hotels-amp-rooms&#038;p=37331"},"modified":"2024-01-02T10:43:46","modified_gmt":"2024-01-02T10:43:46","slug":"lianos-village-hotel-a-naxos","status":"publish","type":"hotels-amp-rooms","link":"https:\/\/www.naxosvacanze.net\/ca\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/","title":{"rendered":"LIANOS VILLAGE"},"content":{"rendered":"\n<p>LIANOS VILLAGE Hotel a Naxos<\/p>\n","protected":false},"featured_media":10805,"template":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>LIANOS VILLAGE Hotel a Naxos - Prenota con NAXOSVACANZE<\/title>\n<meta name=\"description\" content=\"LIANOS VILLAGE confortevole hotel situato sulla spiaggia di Plaka a Naxos. Molte altre soluzioni di alloggio sul nostro sito\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.naxosvacanze.net\/ca\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LIANOS VILLAGE Hotel a Naxos - Prenota con NAXOSVACANZE\" \/>\n<meta property=\"og:description\" content=\"LIANOS VILLAGE confortevole hotel situato sulla spiaggia di Plaka a Naxos. Molte altre soluzioni di alloggio sul nostro sito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.naxosvacanze.net\/ca\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/\" \/>\n<meta property=\"og:site_name\" content=\"NAXOSVACANZE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-02T10:43:46+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.naxosvacanze.net\/wp-content\/uploads\/2021\/01\/LIANOS-VILLAGE-Hotel-81.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/\",\"url\":\"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/\",\"name\":\"LIANOS VILLAGE Hotel a Naxos - Prenota con NAXOSVACANZE\",\"isPartOf\":{\"@id\":\"https:\/\/www.naxosvacanze.net\/wordpress\/#website\"},\"datePublished\":\"2023-12-04T10:59:50+00:00\",\"dateModified\":\"2024-01-02T10:43:46+00:00\",\"description\":\"LIANOS VILLAGE confortevole hotel situato sulla spiaggia di Plaka a Naxos. Molte altre soluzioni di alloggio sul nostro sito\",\"breadcrumb\":{\"@id\":\"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.naxosvacanze.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotels & Rooms\",\"item\":\"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LIANOS VILLAGE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.naxosvacanze.net\/wordpress\/#website\",\"url\":\"https:\/\/www.naxosvacanze.net\/wordpress\/\",\"name\":\"NAXOSVACANZE\",\"description\":\"Il meglio delle Isole Cicladi\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.naxosvacanze.net\/wordpress\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LIANOS VILLAGE Hotel a Naxos - Prenota con NAXOSVACANZE","description":"LIANOS VILLAGE confortevole hotel situato sulla spiaggia di Plaka a Naxos. Molte altre soluzioni di alloggio sul nostro sito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.naxosvacanze.net\/ca\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/","og_locale":"ca_ES","og_type":"article","og_title":"LIANOS VILLAGE Hotel a Naxos - Prenota con NAXOSVACANZE","og_description":"LIANOS VILLAGE confortevole hotel situato sulla spiaggia di Plaka a Naxos. Molte altre soluzioni di alloggio sul nostro sito","og_url":"https:\/\/www.naxosvacanze.net\/ca\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/","og_site_name":"NAXOSVACANZE","article_modified_time":"2024-01-02T10:43:46+00:00","og_image":[{"width":1281,"height":849,"url":"http:\/\/www.naxosvacanze.net\/wp-content\/uploads\/2021\/01\/LIANOS-VILLAGE-Hotel-81.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/","url":"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/","name":"LIANOS VILLAGE Hotel a Naxos - Prenota con NAXOSVACANZE","isPartOf":{"@id":"https:\/\/www.naxosvacanze.net\/wordpress\/#website"},"datePublished":"2023-12-04T10:59:50+00:00","dateModified":"2024-01-02T10:43:46+00:00","description":"LIANOS VILLAGE confortevole hotel situato sulla spiaggia di Plaka a Naxos. Molte altre soluzioni di alloggio sul nostro sito","breadcrumb":{"@id":"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/lianos-village-hotel-a-naxos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.naxosvacanze.net\/"},{"@type":"ListItem","position":2,"name":"Hotels & Rooms","item":"https:\/\/www.naxosvacanze.net\/hotels-amp-rooms\/"},{"@type":"ListItem","position":3,"name":"LIANOS VILLAGE"}]},{"@type":"WebSite","@id":"https:\/\/www.naxosvacanze.net\/wordpress\/#website","url":"https:\/\/www.naxosvacanze.net\/wordpress\/","name":"NAXOSVACANZE","description":"Il meglio delle Isole Cicladi","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.naxosvacanze.net\/wordpress\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/www.naxosvacanze.net\/ca\/wp-json\/wp\/v2\/hotels-amp-rooms\/37331"}],"collection":[{"href":"https:\/\/www.naxosvacanze.net\/ca\/wp-json\/wp\/v2\/hotels-amp-rooms"}],"about":[{"href":"https:\/\/www.naxosvacanze.net\/ca\/wp-json\/wp\/v2\/types\/hotels-amp-rooms"}],"version-history":[{"count":2,"href":"https:\/\/www.naxosvacanze.net\/ca\/wp-json\/wp\/v2\/hotels-amp-rooms\/37331\/revisions"}],"predecessor-version":[{"id":37333,"href":"https:\/\/www.naxosvacanze.net\/ca\/wp-json\/wp\/v2\/hotels-amp-rooms\/37331\/revisions\/37333"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.naxosvacanze.net\/ca\/wp-json\/wp\/v2\/media\/10805"}],"wp:attachment":[{"href":"https:\/\/www.naxosvacanze.net\/ca\/wp-json\/wp\/v2\/media?parent=37331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}